{"id":11009,"date":"2022-05-10T14:26:32","date_gmt":"2022-05-10T12:26:32","guid":{"rendered":"https:\/\/dstoulouse.com\/momo-theater-an-drei-abenden\/"},"modified":"2022-10-04T15:50:27","modified_gmt":"2022-10-04T13:50:27","slug":"momo-trois-spectacles-de-theatre","status":"publish","type":"post","link":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/","title":{"rendered":"Momo &#8211; trois spectacles de th\u00e9\u00e2tre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Momo\u2026 ou la Myst\u00e9rieuse histoire des voleurs de temps et de l&rsquo;enfant qui a rendu aux hommes le temps vol\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c7a vous dit quelque chose ? Mais vous ne connaissez pas encore la r\u00e9alisation de nos \u00e9l\u00e8ves, sous la direction de Sabine Mannigel, qui sera pr\u00e9sent\u00e9e les <strong><s>23<\/s>, 30 et 31 mai<\/strong> \u00e0 l&rsquo;auditorium de l&rsquo;EC2 !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00b4histoire pour enfants de Michael Ende met en sc\u00e8ne la petite fille, Momo. Elle poss\u00e8de le don rare de savoir vraiment bien \u00e9couter et c&rsquo;est ainsi que de nombreux amis viennent toujours la voir. Un jour, les Seigneurs Gris arrivent en ville et volent le temps des gens. Les gens sont de plus en plus malheureux. Avec l&rsquo;aide de Ma\u00eetre Hora et de sa tortue Kassiopeia, Momo tente d&rsquo;arr\u00eater les Seigneurs Gris et de rendre le temps vol\u00e9 aux humains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez d\u00e8s \u00e0 pr\u00e9sent r\u00e9server des places en cliquant sur ce lien : <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=djhuVWFYykyplkazaNIxMZswiru9gwBCvBL56Z_b_T5UNkhKUjBCWlRGV1E4NFBJQ1BZNFdKNk5MWC4u\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9servation de la repr\u00e9sentation de th\u00e9\u00e2tre Momo.<\/a><br>Le paiement se fait sur place le soir m\u00eame.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022_1.png\" alt=\"Deutsche Schule Toulouse, Theaterplakat Momo zwei M\u00e4dchen\" class=\"wp-image-11002\" srcset=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022_1.png 750w, https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022_1-300x200.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Momo\u2026 ou la Myst\u00e9rieuse histoire des voleurs de temps et de l&rsquo;enfant qui a rendu aux hommes le temps vol\u00e9. \u00c7a vous dit quelque chose ? Mais vous ne connaissez&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/\" class=\"gdlr-button with-border excerpt-read-more\">En savoir plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":11001,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"iawp_total_views":9,"footnotes":""},"categories":[73,50,51,68,45,63],"tags":[],"class_list":["post-11009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annee-scolaire-2021-22","category-college-lycee","category-dst-fr","category-dst-kulturelles-fr","category-la-vie-a-lecole","category-schuljahr-2021-22-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"og:description\" content=\"Momo\u2026 ou la Myst\u00e9rieuse histoire des voleurs de temps et de l&rsquo;enfant qui a rendu aux hommes le temps vol\u00e9. \u00c7a vous dit quelque chose ? Mais vous ne connaissez... En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T12:26:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T13:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicole KN\u00dcPPEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole KN\u00dcPPEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/\"},\"author\":{\"name\":\"Nicole KN\u00dcPPEL\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\"},\"headline\":\"Momo &#8211; trois spectacles de th\u00e9\u00e2tre\",\"datePublished\":\"2022-05-10T12:26:32+00:00\",\"dateModified\":\"2022-10-04T13:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/\"},\"wordCount\":189,\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_momo_2022.png\",\"articleSection\":[\"Ann\u00e9e scolaire 2021\\\/22\",\"Coll\u00e8ge \\\/ Lyc\u00e9e\",\"DST\",\"DST Kulturelles\",\"La vie \u00e0 l\u2019\u00e9cole\",\"Schuljahr 2021\\\/22\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/\",\"name\":\"Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_momo_2022.png\",\"datePublished\":\"2022-05-10T12:26:32+00:00\",\"dateModified\":\"2022-10-04T13:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_momo_2022.png\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_momo_2022.png\",\"width\":750,\"height\":330,\"caption\":\"Deutsche Schule Toulouse, Theaterplakat Momo f\u00fcnf M\u00e4dchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/momo-trois-spectacles-de-theatre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Momo &#8211; trois spectacles de th\u00e9\u00e2tre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"name\":\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"description\":\"Wir bilden das Europa von morgen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dstoulouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\",\"name\":\"Deutsche Schule Toulouse\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"width\":149,\"height\":107,\"caption\":\"Deutsche Schule Toulouse\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\",\"name\":\"Nicole KN\u00dcPPEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/","og_locale":"fr_FR","og_type":"article","og_title":"Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","og_description":"Momo\u2026 ou la Myst\u00e9rieuse histoire des voleurs de temps et de l&rsquo;enfant qui a rendu aux hommes le temps vol\u00e9. \u00c7a vous dit quelque chose ? Mais vous ne connaissez... En savoir plus","og_url":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/","og_site_name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","article_published_time":"2022-05-10T12:26:32+00:00","article_modified_time":"2022-10-04T13:50:27+00:00","og_image":[{"width":750,"height":330,"url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png","type":"image\/png"}],"author":"Nicole KN\u00dcPPEL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicole KN\u00dcPPEL","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#article","isPartOf":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/"},"author":{"name":"Nicole KN\u00dcPPEL","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975"},"headline":"Momo &#8211; trois spectacles de th\u00e9\u00e2tre","datePublished":"2022-05-10T12:26:32+00:00","dateModified":"2022-10-04T13:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/"},"wordCount":189,"publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png","articleSection":["Ann\u00e9e scolaire 2021\/22","Coll\u00e8ge \/ Lyc\u00e9e","DST","DST Kulturelles","La vie \u00e0 l\u2019\u00e9cole","Schuljahr 2021\/22"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/","url":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/","name":"Momo - trois spectacles de th\u00e9\u00e2tre - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","isPartOf":{"@id":"https:\/\/dstoulouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#primaryimage"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png","datePublished":"2022-05-10T12:26:32+00:00","dateModified":"2022-10-04T13:50:27+00:00","breadcrumb":{"@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#primaryimage","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_momo_2022.png","width":750,"height":330,"caption":"Deutsche Schule Toulouse, Theaterplakat Momo f\u00fcnf M\u00e4dchen"},{"@type":"BreadcrumbList","@id":"https:\/\/dstoulouse.com\/fr\/momo-trois-spectacles-de-theatre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dstoulouse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Momo &#8211; trois spectacles de th\u00e9\u00e2tre"}]},{"@type":"WebSite","@id":"https:\/\/dstoulouse.com\/#website","url":"https:\/\/dstoulouse.com\/","name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","description":"Wir bilden das Europa von morgen","publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dstoulouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dstoulouse.com\/#organization","name":"Deutsche Schule Toulouse","url":"https:\/\/dstoulouse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","width":149,"height":107,"caption":"Deutsche Schule Toulouse"},"image":{"@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975","name":"Nicole KN\u00dcPPEL"}]}},"_links":{"self":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/11009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/comments?post=11009"}],"version-history":[{"count":0,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/11009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media\/11001"}],"wp:attachment":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media?parent=11009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/categories?post=11009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/tags?post=11009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}