{"id":13975,"date":"2023-06-21T11:47:43","date_gmt":"2023-06-21T09:47:43","guid":{"rendered":"https:\/\/dstoulouse.com\/maltalente-der-faelschergeneration-2023\/"},"modified":"2023-06-21T11:57:30","modified_gmt":"2023-06-21T09:57:30","slug":"generation-2023-des-meilleurs-copistes","status":"publish","type":"post","link":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/","title":{"rendered":"Generation 2023 des meilleurs Copistes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s 10 semaines de peinture et \u00e9change en groupes dans le cadre du projet trilingue, nos \u00e9l\u00e8ves ont pr\u00e9sent\u00e9, avec une grande fiert\u00e9, leurs \u0153uvres la semaine derni\u00e8re (jeudi 15 Juin) \u00e0 l&rsquo;occasion d&rsquo;un vernissage avec remise de prix !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une manifestation sympathique, qui n&rsquo;avait pas pu avoir lieu depuis 2019 en raison du Covid, et o\u00f9 un jury compos\u00e9 de membres de la direction (Dr. Weinert, Madlen Coutant pour la DST et Madame Camin du Coll\u00e8ge Victor Hugo) ont eu la difficile t\u00e2che de choisir les meilleurs copistes.<br>Les repr\u00e9sentants des deux directions, qui ont soulign\u00e9 le r\u00f4le important de ce projet cr\u00e9atif et interculturel, se sont \u00e9galement montr\u00e9s impressionn\u00e9s par le talent des \u00e9l\u00e8ves et ont f\u00e9licit\u00e9 \u00e0 plusieurs reprises les peintres talentueux, dont les \u0153uvres sont accroch\u00e9es au 1er \u00e9tage du lyc\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder1.jpg\" alt=\"Deutsche Schule Toulouse, Bilder der F\u00e4lscherwerkstatt im trilingualen Unterricht\" class=\"wp-image-13957\" srcset=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder1.jpg 750w, https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder1-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ce projet trilingue a pour but de proposer une pratique picturale approfondie aux \u00e9l\u00e8ves mais \u00e9galement de renforcer leur exp\u00e9rience du travail en \u00e9quipe et d&rsquo;\u00e9largir leurs connaissances en langues \u00e9trang\u00e8res.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder2.jpg\" alt=\"Deutsche Schule Toulouse, Bilder der F\u00e4lscherwerkstatt im trilingualen Unterricht\" class=\"wp-image-13960\" srcset=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder2.jpg 750w, https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder2-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les gagnants de tous les groupes, qui ont \u00e9t\u00e9 accompagn\u00e9s dans ce projet sur les 2 semestres par les 3 professeurs d&rsquo;arts plastiques (Frau Brunerie pour la DST, Mrs Southwell pour E31 et Madame Ristenko pour Victor Hugo) ont pu se r\u00e9jouir du mat\u00e9riel d&rsquo;arts plastiques qui leur a \u00e9t\u00e9 offert.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder3.jpg\" alt=\"Deutsche Schule Toulouse, Bilder der F\u00e4lscherwerkstatt im trilingualen Unterricht\" class=\"wp-image-13963\" srcset=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder3.jpg 750w, https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_bilder3-300x200.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s 10 semaines de peinture et \u00e9change en groupes dans le cadre du projet trilingue, nos \u00e9l\u00e8ves ont pr\u00e9sent\u00e9, avec une grande fiert\u00e9, leurs \u0153uvres la semaine derni\u00e8re (jeudi 15&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/\" class=\"gdlr-button with-border excerpt-read-more\">En savoir plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":13968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"iawp_total_views":14,"footnotes":""},"categories":[50,45,75],"tags":[],"class_list":["post-13975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-college-lycee","category-la-vie-a-lecole","category-schuljahr-2022-23-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s 10 semaines de peinture et \u00e9change en groupes dans le cadre du projet trilingue, nos \u00e9l\u00e8ves ont pr\u00e9sent\u00e9, avec une grande fiert\u00e9, leurs \u0153uvres la semaine derni\u00e8re (jeudi 15... En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T09:47:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T09:57:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole KN\u00dcPPEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole KN\u00dcPPEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/\"},\"author\":{\"name\":\"Nicole KN\u00dcPPEL\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\"},\"headline\":\"Generation 2023 des meilleurs Copistes\",\"datePublished\":\"2023-06-21T09:47:43+00:00\",\"dateModified\":\"2023-06-21T09:57:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_trili_faelscherwerkstatt.jpg\",\"articleSection\":[\"Coll\u00e8ge \\\/ Lyc\u00e9e\",\"La vie \u00e0 l\u2019\u00e9cole\",\"Schuljahr 2022\\\/23\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/\",\"name\":\"Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_trili_faelscherwerkstatt.jpg\",\"datePublished\":\"2023-06-21T09:47:43+00:00\",\"dateModified\":\"2023-06-21T09:57:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_trili_faelscherwerkstatt.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_trili_faelscherwerkstatt.jpg\",\"width\":750,\"height\":330,\"caption\":\"Deutsche Schule Toulouse, Preistr\u00e4gerinnnn und Preistr\u00e4ger der F\u00e4lscherwerkstatt im trilingualen Unterricht\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/generation-2023-des-meilleurs-copistes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Generation 2023 des meilleurs Copistes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"name\":\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"description\":\"Wir bilden das Europa von morgen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dstoulouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\",\"name\":\"Deutsche Schule Toulouse\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"width\":149,\"height\":107,\"caption\":\"Deutsche Schule Toulouse\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\",\"name\":\"Nicole KN\u00dcPPEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/","og_locale":"fr_FR","og_type":"article","og_title":"Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","og_description":"Apr\u00e8s 10 semaines de peinture et \u00e9change en groupes dans le cadre du projet trilingue, nos \u00e9l\u00e8ves ont pr\u00e9sent\u00e9, avec une grande fiert\u00e9, leurs \u0153uvres la semaine derni\u00e8re (jeudi 15... En savoir plus","og_url":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/","og_site_name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","article_published_time":"2023-06-21T09:47:43+00:00","article_modified_time":"2023-06-21T09:57:30+00:00","og_image":[{"width":750,"height":330,"url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg","type":"image\/jpeg"}],"author":"Nicole KN\u00dcPPEL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicole KN\u00dcPPEL","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#article","isPartOf":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/"},"author":{"name":"Nicole KN\u00dcPPEL","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975"},"headline":"Generation 2023 des meilleurs Copistes","datePublished":"2023-06-21T09:47:43+00:00","dateModified":"2023-06-21T09:57:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/"},"wordCount":240,"publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg","articleSection":["Coll\u00e8ge \/ Lyc\u00e9e","La vie \u00e0 l\u2019\u00e9cole","Schuljahr 2022\/23"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/","url":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/","name":"Generation 2023 des meilleurs Copistes - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","isPartOf":{"@id":"https:\/\/dstoulouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#primaryimage"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg","datePublished":"2023-06-21T09:47:43+00:00","dateModified":"2023-06-21T09:57:30+00:00","breadcrumb":{"@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#primaryimage","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_trili_faelscherwerkstatt.jpg","width":750,"height":330,"caption":"Deutsche Schule Toulouse, Preistr\u00e4gerinnnn und Preistr\u00e4ger der F\u00e4lscherwerkstatt im trilingualen Unterricht"},{"@type":"BreadcrumbList","@id":"https:\/\/dstoulouse.com\/fr\/generation-2023-des-meilleurs-copistes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dstoulouse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Generation 2023 des meilleurs Copistes"}]},{"@type":"WebSite","@id":"https:\/\/dstoulouse.com\/#website","url":"https:\/\/dstoulouse.com\/","name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","description":"Wir bilden das Europa von morgen","publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dstoulouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dstoulouse.com\/#organization","name":"Deutsche Schule Toulouse","url":"https:\/\/dstoulouse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","width":149,"height":107,"caption":"Deutsche Schule Toulouse"},"image":{"@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975","name":"Nicole KN\u00dcPPEL"}]}},"_links":{"self":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/13975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/comments?post=13975"}],"version-history":[{"count":0,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/13975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media\/13968"}],"wp:attachment":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media?parent=13975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/categories?post=13975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/tags?post=13975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}