{"id":19917,"date":"2024-12-16T16:09:50","date_gmt":"2024-12-16T15:09:50","guid":{"rendered":"https:\/\/dstoulouse.com\/multikultureller-empfang-fuer-den-heiligen-nikolaus\/"},"modified":"2024-12-16T16:12:57","modified_gmt":"2024-12-16T15:12:57","slug":"saint-nicolas-accueilli-par-assemblee-multiculturelle","status":"publish","type":"post","link":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/","title":{"rendered":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nos \u00e9l\u00e8ves du CP et CE1 r\u00e9unis avec les CP de l\u2019Ecole Primaire Lucie Aubrac (Colomiers) et de l\u2019International School of Toulouse ont accueilli cette ann\u00e9e le Saint Nicolas ensemble ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019assembl\u00e9e multiculturelle fut attentive, impatiente et pleine d\u2019espoir \u00e0 l\u2019arriv\u00e9e du Saint Nicolas, venu avec des sacs bien remplis. Apr\u00e8s des chansons et comptines fran\u00e7aises, anglaises et allemandes, le Saint Nicolas a \u00e9chang\u00e9 avec chaque \u00e9l\u00e8ve tout en lui remettant un petit cadeau.. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un bel \u00e9v\u00e8nement qui contribue \u00e0 renforcer les liens entre les \u00e9l\u00e8ves de cultures diff\u00e9rentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos \u00e9l\u00e8ves du CP et CE1 r\u00e9unis avec les CP de l\u2019Ecole Primaire Lucie Aubrac (Colomiers) et de l\u2019International School of Toulouse ont accueilli cette ann\u00e9e le Saint Nicolas ensemble&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/\" class=\"gdlr-button with-border excerpt-read-more\">En savoir plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":19912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"iawp_total_views":25,"footnotes":""},"categories":[111,49,45,110],"tags":[],"class_list":["post-19917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annee-scolaire-2024-25","category-ecole-elementaire","category-la-vie-a-lecole","category-schuljahr-2024-25-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"og:description\" content=\"Nos \u00e9l\u00e8ves du CP et CE1 r\u00e9unis avec les CP de l\u2019Ecole Primaire Lucie Aubrac (Colomiers) et de l\u2019International School of Toulouse ont accueilli cette ann\u00e9e le Saint Nicolas ensemble... En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T15:09:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T15:12:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicole KN\u00dcPPEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole KN\u00dcPPEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/\"},\"author\":{\"name\":\"Nicole KN\u00dcPPEL\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\"},\"headline\":\"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle\",\"datePublished\":\"2024-12-16T15:09:50+00:00\",\"dateModified\":\"2024-12-16T15:12:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/\"},\"wordCount\":111,\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_nikolaus_2024.png\",\"articleSection\":[\"Ann\u00e9e scolaire 2024\\\/25\",\"\u00c9cole \u00e9l\u00e9mentaire\",\"La vie \u00e0 l\u2019\u00e9cole\",\"Schuljahr 2024\\\/25\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/\",\"name\":\"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_nikolaus_2024.png\",\"datePublished\":\"2024-12-16T15:09:50+00:00\",\"dateModified\":\"2024-12-16T15:12:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_nikolaus_2024.png\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst_nikolaus_2024.png\",\"width\":750,\"height\":330,\"caption\":\"Bildcollage: Gebastelter Nikol\u00e4use und Nikolaus mit einer Kindergruppe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/saint-nicolas-accueilli-par-assemblee-multiculturelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"name\":\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"description\":\"Wir bilden das Europa von morgen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dstoulouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\",\"name\":\"Deutsche Schule Toulouse\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"width\":149,\"height\":107,\"caption\":\"Deutsche Schule Toulouse\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\",\"name\":\"Nicole KN\u00dcPPEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","og_description":"Nos \u00e9l\u00e8ves du CP et CE1 r\u00e9unis avec les CP de l\u2019Ecole Primaire Lucie Aubrac (Colomiers) et de l\u2019International School of Toulouse ont accueilli cette ann\u00e9e le Saint Nicolas ensemble... En savoir plus","og_url":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/","og_site_name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","article_published_time":"2024-12-16T15:09:50+00:00","article_modified_time":"2024-12-16T15:12:57+00:00","og_image":[{"width":750,"height":330,"url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png","type":"image\/png"}],"author":"Nicole KN\u00dcPPEL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicole KN\u00dcPPEL","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#article","isPartOf":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/"},"author":{"name":"Nicole KN\u00dcPPEL","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975"},"headline":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle","datePublished":"2024-12-16T15:09:50+00:00","dateModified":"2024-12-16T15:12:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/"},"wordCount":111,"publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png","articleSection":["Ann\u00e9e scolaire 2024\/25","\u00c9cole \u00e9l\u00e9mentaire","La vie \u00e0 l\u2019\u00e9cole","Schuljahr 2024\/25"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/","url":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/","name":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","isPartOf":{"@id":"https:\/\/dstoulouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#primaryimage"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png","datePublished":"2024-12-16T15:09:50+00:00","dateModified":"2024-12-16T15:12:57+00:00","breadcrumb":{"@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#primaryimage","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst_nikolaus_2024.png","width":750,"height":330,"caption":"Bildcollage: Gebastelter Nikol\u00e4use und Nikolaus mit einer Kindergruppe"},{"@type":"BreadcrumbList","@id":"https:\/\/dstoulouse.com\/fr\/saint-nicolas-accueilli-par-assemblee-multiculturelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dstoulouse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Saint Nicolas accueilli par une assembl\u00e9e multiculturelle"}]},{"@type":"WebSite","@id":"https:\/\/dstoulouse.com\/#website","url":"https:\/\/dstoulouse.com\/","name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","description":"Wir bilden das Europa von morgen","publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dstoulouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dstoulouse.com\/#organization","name":"Deutsche Schule Toulouse","url":"https:\/\/dstoulouse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","width":149,"height":107,"caption":"Deutsche Schule Toulouse"},"image":{"@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975","name":"Nicole KN\u00dcPPEL"}]}},"_links":{"self":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/19917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/comments?post=19917"}],"version-history":[{"count":1,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/19917\/revisions"}],"predecessor-version":[{"id":19919,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/19917\/revisions\/19919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media\/19912"}],"wp:attachment":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media?parent=19917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/categories?post=19917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/tags?post=19917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}