{"id":21067,"date":"2025-05-10T15:29:54","date_gmt":"2025-05-10T13:29:54","guid":{"rendered":"https:\/\/dstoulouse.com\/medienkompetenz-kindergartenalter-abend-fuer-eltern\/"},"modified":"2025-05-19T09:22:52","modified_gmt":"2025-05-19T07:22:52","slug":"enfants-et-ecran-soiree-parents","status":"publish","type":"post","link":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/","title":{"rendered":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les \u00e9crans font aujourd\u2019hui partie int\u00e9grante du quotidien \u2013 non seulement pour les adultes, mais de plus en plus aussi pour les tout-petits. Le temps pass\u00e9 devant les tablettes, smartphones ou t\u00e9l\u00e9viseurs a consid\u00e9rablement augment\u00e9 ces derni\u00e8res ann\u00e9es, m\u00eame chez les jeunes enfants. Mais quelles sont les cons\u00e9quences sur leur d\u00e9veloppement ? Quels sont les risques connus ? Et comment les parents peuvent-ils accompagner leurs enfants de mani\u00e8re responsable dans ce monde num\u00e9rique ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est \u00e0 ces questions qu\u2019a r\u00e9pondu la Dre Christine Chollet, p\u00e9diatre exp\u00e9riment\u00e9e, lors d\u2019une soir\u00e9e th\u00e9matique organis\u00e9e \u00e0 notre Ecole Maternelle. Elle a ainsi partag\u00e9 ses connaissances avec les parents et leur a donn\u00e9 de nombreuses pistes concr\u00e8tes pour un usage r\u00e9fl\u00e9chi et adapt\u00e9 des \u00e9crans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 son exp\u00e9rience de terrain et \u00e0 des exemples parlants, la Dre Chollet leur a montr\u00e9 non seulement les effets possibles d\u2019une exposition excessive aux \u00e9crans sur le sommeil, le d\u00e9veloppement physique, la vision et les capacit\u00e9s d\u2019apprentissage des enfants mais leur a aussi indiqu\u00e9 des pistes de \u00ab bonne conduite \u00bb afin que les enfants puissent d\u00e9couvrir le monde num\u00e9rique avec curiosit\u00e9, mais en toute s\u00e9curit\u00e9 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00catre un mod\u00e8le <\/strong>: Les enfants imitent les adultes. Un parent souvent absorb\u00e9 par son t\u00e9l\u00e9phone transmet un message \u2013 m\u00eame involontairement<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9finir un cadre <\/strong>: Ce sont les parents qui d\u00e9cident du moment, de la dur\u00e9e et du contenu. Il est essentiel de choisir des contenus adapt\u00e9s \u00e0 l\u2019\u00e2ge et de fixer des limites claires.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9couvrir ensemble<\/strong> : Le monde num\u00e9rique ne devrait pas \u00eatre explor\u00e9 seul. Regarder, expliquer et commenter ensemble cr\u00e9e de la proximit\u00e9 et favorise la compr\u00e9hension.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Encourager le dialogue<\/strong> : Discuter avec son enfant de ce qu\u2019il a vu stimule le langage, l\u2019esprit critique et pr\u00e9pare un usage plus autonome et \u00e9quilibr\u00e9 des m\u00e9dias.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Merci aux organisateurs de cette soir\u00e9e qui a permis \u00e0 nos parents de comprendre les risques d\u2019une sur-exposition aux \u00e9crans et de leur proposer des pistes pour un usage accompagn\u00e9, conscient et bienveillant pour le bien-\u00eatre des leurs enfants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9crans font aujourd\u2019hui partie int\u00e9grante du quotidien \u2013 non seulement pour les adultes, mais de plus en plus aussi pour les tout-petits. Le temps pass\u00e9 devant les tablettes, smartphones&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/\" class=\"gdlr-button with-border excerpt-read-more\">En savoir plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":21010,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"iawp_total_views":9,"footnotes":""},"categories":[111,48,45,110],"tags":[],"class_list":["post-21067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annee-scolaire-2024-25","category-ecole-maternelle","category-la-vie-a-lecole","category-schuljahr-2024-25-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9crans font aujourd\u2019hui partie int\u00e9grante du quotidien \u2013 non seulement pour les adultes, mais de plus en plus aussi pour les tout-petits. Le temps pass\u00e9 devant les tablettes, smartphones... En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-10T13:29:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-19T07:22:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole KN\u00dcPPEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole KN\u00dcPPEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/\"},\"author\":{\"name\":\"Nicole KN\u00dcPPEL\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\"},\"headline\":\"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle\",\"datePublished\":\"2025-05-10T13:29:54+00:00\",\"dateModified\":\"2025-05-19T07:22:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/\"},\"wordCount\":388,\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-info-medien-kiga-1.jpg\",\"articleSection\":[\"Ann\u00e9e scolaire 2024\\\/25\",\"\u00c9cole maternelle\",\"La vie \u00e0 l\u2019\u00e9cole\",\"Schuljahr 2024\\\/25\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/\",\"name\":\"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-info-medien-kiga-1.jpg\",\"datePublished\":\"2025-05-10T13:29:54+00:00\",\"dateModified\":\"2025-05-19T07:22:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-info-medien-kiga-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-info-medien-kiga-1.jpg\",\"width\":750,\"height\":330,\"caption\":\"Deutsche Schule Toulouse, Elternabend, Zuh\u00f6rende und eine Rednerin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/enfants-et-ecran-soiree-parents\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dstoulouse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#website\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"name\":\"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule\",\"description\":\"Wir bilden das Europa von morgen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dstoulouse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#organization\",\"name\":\"Deutsche Schule Toulouse\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dstoulouse.com\\\/wp-content\\\/uploads\\\/dst-logo.jpg\",\"width\":149,\"height\":107,\"caption\":\"Deutsche Schule Toulouse\"},\"image\":{\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dstoulouse.com\\\/#\\\/schema\\\/person\\\/0b48fa4e25c55048d6e0bb98b1696975\",\"name\":\"Nicole KN\u00dcPPEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/","og_locale":"fr_FR","og_type":"article","og_title":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","og_description":"Les \u00e9crans font aujourd\u2019hui partie int\u00e9grante du quotidien \u2013 non seulement pour les adultes, mais de plus en plus aussi pour les tout-petits. Le temps pass\u00e9 devant les tablettes, smartphones... En savoir plus","og_url":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/","og_site_name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","article_published_time":"2025-05-10T13:29:54+00:00","article_modified_time":"2025-05-19T07:22:52+00:00","og_image":[{"width":750,"height":330,"url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg","type":"image\/jpeg"}],"author":"Nicole KN\u00dcPPEL","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicole KN\u00dcPPEL","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#article","isPartOf":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/"},"author":{"name":"Nicole KN\u00dcPPEL","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975"},"headline":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle","datePublished":"2025-05-10T13:29:54+00:00","dateModified":"2025-05-19T07:22:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/"},"wordCount":388,"publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg","articleSection":["Ann\u00e9e scolaire 2024\/25","\u00c9cole maternelle","La vie \u00e0 l\u2019\u00e9cole","Schuljahr 2024\/25"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/","url":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/","name":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle - Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","isPartOf":{"@id":"https:\/\/dstoulouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#primaryimage"},"image":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#primaryimage"},"thumbnailUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg","datePublished":"2025-05-10T13:29:54+00:00","dateModified":"2025-05-19T07:22:52+00:00","breadcrumb":{"@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#primaryimage","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-info-medien-kiga-1.jpg","width":750,"height":330,"caption":"Deutsche Schule Toulouse, Elternabend, Zuh\u00f6rende und eine Rednerin"},{"@type":"BreadcrumbList","@id":"https:\/\/dstoulouse.com\/fr\/enfants-et-ecran-soiree-parents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dstoulouse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Enfants et \u00e9crans : une soir\u00e9e th\u00e9matique pour les parents de notre Ecole Maternelle"}]},{"@type":"WebSite","@id":"https:\/\/dstoulouse.com\/#website","url":"https:\/\/dstoulouse.com\/","name":"Deutsche Schule Toulouse: Exzellente Deutsche Auslandsschule mit Kindergarten, Grundschule und weiterf&uuml;hrender Schule","description":"Wir bilden das Europa von morgen","publisher":{"@id":"https:\/\/dstoulouse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dstoulouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dstoulouse.com\/#organization","name":"Deutsche Schule Toulouse","url":"https:\/\/dstoulouse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/","url":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","contentUrl":"https:\/\/dstoulouse.com\/wp-content\/uploads\/dst-logo.jpg","width":149,"height":107,"caption":"Deutsche Schule Toulouse"},"image":{"@id":"https:\/\/dstoulouse.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dstoulouse.com\/#\/schema\/person\/0b48fa4e25c55048d6e0bb98b1696975","name":"Nicole KN\u00dcPPEL"}]}},"_links":{"self":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/21067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/comments?post=21067"}],"version-history":[{"count":1,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/21067\/revisions"}],"predecessor-version":[{"id":21069,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/posts\/21067\/revisions\/21069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media\/21010"}],"wp:attachment":[{"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/media?parent=21067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/categories?post=21067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dstoulouse.com\/fr\/wp-json\/wp\/v2\/tags?post=21067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}